{"id":2064,"date":"2016-07-24T09:56:31","date_gmt":"2016-07-24T09:56:31","guid":{"rendered":"https:\/\/losmolinoshotel.com\/galeria\/"},"modified":"2025-09-16T22:04:12","modified_gmt":"2025-09-16T22:04:12","slug":"gallery","status":"publish","type":"page","link":"https:\/\/losmolinoshotel.com\/en\/gallery\/","title":{"rendered":"Gallery"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<!-- Section Gallery --><div class=\"section \" id=\"portfolio\"><div class=\"wrapper-inner\"><!-- Gallery Filter --><div class=\"widget-filter-top\"><ul><li class=\"active\"><a href=\"#\" data-filter=\"*\">ALL PHOTOS<\/a><\/li><li><a href=\"#\" data-filter=\".events\">Events<\/a><\/li><li><a href=\"#\" data-filter=\".hotel-en\">Hotel<\/a><\/li><li><a href=\"#\" data-filter=\".restaurant\">Restaurant<\/a><\/li><li><a href=\"#\" data-filter=\".spa-wellness-club-en\">Spa &amp; Wellness Club<\/a><\/li><li><a href=\"#\" data-filter=\".tour-en\">Tour<\/a><\/li><li><a href=\"#\" data-filter=\".weddings\">Weddings<\/a><\/li><\/ul><\/div><!-- Gallery Filter End --><!-- Gallery List --><div class=\"widget-gallery-grid\"><div class=\"row\"><div class=\"col-lg-3 col-md-4 col-sm-6 col-xs-12 isotope-item \"><div class=\"gallery-item\"><a href=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2023\/08\/hacienda-los-molinos-boutique-hotel-restaurante.webp\" data-background=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2023\/08\/hacienda-los-molinos-boutique-hotel-restaurante.webp\" title=\"Restaurant\" class=\"grandium-popup-gallery\"><\/a><\/div><\/div><div class=\"col-lg-3 col-md-4 col-sm-6 col-xs-12 isotope-item \"><div class=\"gallery-item\"><a href=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2023\/08\/hacienda-los-molinos-boutique-hotel-restaurante-2.webp\" data-background=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2023\/08\/hacienda-los-molinos-boutique-hotel-restaurante-2.webp\" title=\"Restaurant\" class=\"grandium-popup-gallery\"><\/a><\/div><\/div><div class=\"col-lg-3 col-md-4 col-sm-6 col-xs-12 isotope-item tour-en\"><div class=\"gallery-item\"><a href=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Canyon-Hike-Ceriana-gallery-1-min.jpg\" data-background=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Canyon-Hike-Ceriana-gallery-1-min.jpg\" title=\"Tour\" class=\"grandium-popup-gallery\"><\/a><\/div><\/div><div class=\"col-lg-3 col-md-4 col-sm-6 col-xs-12 isotope-item spa-wellness-club-en\"><div class=\"gallery-item\"><a href=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Spa-gallery-7-min.jpg\" data-background=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Spa-gallery-7-min.jpg\" title=\"Spa\" class=\"grandium-popup-gallery\"><\/a><\/div><\/div><div class=\"col-lg-3 col-md-4 col-sm-6 col-xs-12 isotope-item spa-wellness-club-en\"><div class=\"gallery-item\"><a href=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Spa-gallery-8-min.jpg\" data-background=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Spa-gallery-8-min.jpg\" title=\"Spa\" class=\"grandium-popup-gallery\"><\/a><\/div><\/div><div class=\"col-lg-3 col-md-4 col-sm-6 col-xs-12 isotope-item hotel-en\"><div class=\"gallery-item\"><a href=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Galeria-Habitaciones-10-min.jpg\" data-background=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Galeria-Habitaciones-10-min.jpg\" title=\"Hotel\" class=\"grandium-popup-gallery\"><\/a><\/div><\/div><div class=\"col-lg-3 col-md-4 col-sm-6 col-xs-12 isotope-item hotel-en\"><div class=\"gallery-item\"><a href=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Galeria-Restaurante-4-min.jpg\" data-background=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Galeria-Restaurante-4-min.jpg\" title=\"Hotel\" class=\"grandium-popup-gallery\"><\/a><\/div><\/div><div class=\"col-lg-3 col-md-4 col-sm-6 col-xs-12 isotope-item weddings\"><div class=\"gallery-item\"><a href=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/boda-gallery-6-min.jpg\" data-background=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/boda-gallery-6-min.jpg\" title=\"Weddings\" class=\"grandium-popup-gallery\"><\/a><\/div><\/div><div class=\"col-lg-3 col-md-4 col-sm-6 col-xs-12 isotope-item events\"><div class=\"gallery-item\"><a href=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/evento-social-gallery-10-min.jpg\" data-background=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/evento-social-gallery-10-min.jpg\" title=\"Events\" class=\"grandium-popup-gallery\"><\/a><\/div><\/div><div class=\"col-lg-3 col-md-4 col-sm-6 col-xs-12 isotope-item events\"><div class=\"gallery-item\"><a href=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/evento-social-gallery-6-min.jpg\" data-background=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/evento-social-gallery-6-min.jpg\" title=\"Events\" class=\"grandium-popup-gallery\"><\/a><\/div><\/div><div class=\"col-lg-3 col-md-4 col-sm-6 col-xs-12 isotope-item restaurant\"><div class=\"gallery-item\"><a href=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Galeria-Restaurante-8-min.jpg\" data-background=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Galeria-Restaurante-8-min.jpg\" title=\"Restaurant\" class=\"grandium-popup-gallery\"><\/a><\/div><\/div><div class=\"col-lg-3 col-md-4 col-sm-6 col-xs-12 isotope-item events\"><div class=\"gallery-item\"><a href=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Canyon-Hike-Ceriana-gallery-7-min.jpg\" data-background=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/06\/Canyon-Hike-Ceriana-gallery-7-min.jpg\" title=\"Tour\" class=\"grandium-popup-gallery\"><\/a><\/div><\/div><\/div><\/div><!-- Gallery List End --><\/div><\/div><!-- Section Gallery End -->[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1592503436157{padding-right: 100px !important;padding-left: 100px !important;}&#8221;][vc_column][vc_empty_space height=&#8221;50px&#8221;][vc_custom_heading text=&#8221;Bodas&#8221; font_container=&#8221;tag:h1|text_align:center&#8221;][vc_media_grid element_width=&#8221;3&#8243; grid_id=&#8221;vc_gid:1592503282108-455211a5-af89-2&#8243; include=&#8221;1967,1966,1965,1963&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1592503436157{padding-right: 100px !important;padding-left: 100px !important;}&#8221;][vc_column][vc_empty_space height=&#8221;50px&#8221;][vc_custom_heading text=&#8221;Bodas&#8221; font_container=&#8221;tag:h1|text_align:center&#8221;][vc_media_grid element_width=&#8221;3&#8243; grid_id=&#8221;vc_gid:1592503282108-455211a5-af89-2&#8243; include=&#8221;1967,1966,1965,1963&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":1973,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"fullwidth-page.php","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-2064","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gallery Los Molinos Boutique Hotel | hotel, spa, events &amp; tours<\/title>\n<meta name=\"description\" content=\"Explore the gallery of Los Molinos Boutique Hotel. Discover our hotel, spa, events, and tours in Boquete, Chiriqu\u00ed, Panama\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/losmolinoshotel.com\/en\/gallery\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gallery Los Molinos Boutique Hotel | hotel, spa, events &amp; tours\" \/>\n<meta property=\"og:description\" content=\"Explore the gallery of Los Molinos Boutique Hotel. Discover our hotel, spa, events, and tours in Boquete, Chiriqu\u00ed, Panama\" \/>\n<meta property=\"og:url\" content=\"https:\/\/losmolinoshotel.com\/en\/gallery\/\" \/>\n<meta property=\"og:site_name\" content=\"Hacienda Los Molinos Boutique Hotel\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T22:04:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/10\/header_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/losmolinoshotel.com\\\/en\\\/gallery\\\/\",\"url\":\"https:\\\/\\\/losmolinoshotel.com\\\/en\\\/gallery\\\/\",\"name\":\"Gallery Los Molinos Boutique Hotel | hotel, spa, events & tours\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/losmolinoshotel.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/losmolinoshotel.com\\\/en\\\/gallery\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/losmolinoshotel.com\\\/en\\\/gallery\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/losmolinoshotel.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/header_4.jpg\",\"datePublished\":\"2016-07-24T09:56:31+00:00\",\"dateModified\":\"2025-09-16T22:04:12+00:00\",\"description\":\"Explore the gallery of Los Molinos Boutique Hotel. Discover our hotel, spa, events, and tours in Boquete, Chiriqu\u00ed, Panama\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/losmolinoshotel.com\\\/en\\\/gallery\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/losmolinoshotel.com\\\/en\\\/gallery\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/losmolinoshotel.com\\\/en\\\/gallery\\\/#primaryimage\",\"url\":\"https:\\\/\\\/losmolinoshotel.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/header_4.jpg\",\"contentUrl\":\"https:\\\/\\\/losmolinoshotel.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/header_4.jpg\",\"width\":1920,\"height\":705,\"caption\":\"Cafeter\u00edas en Boquete, Chiriqu\u00ed | Disfruta en Hacienda Los Molinos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/losmolinoshotel.com\\\/en\\\/gallery\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/losmolinoshotel.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gallery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/losmolinoshotel.com\\\/#website\",\"url\":\"https:\\\/\\\/losmolinoshotel.com\\\/\",\"name\":\"Hacienda Los Molinos Boutique Hotel\",\"description\":\"Hotel en Boquete, Panam\u00e1\",\"publisher\":{\"@id\":\"https:\\\/\\\/losmolinoshotel.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/losmolinoshotel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/losmolinoshotel.com\\\/#organization\",\"name\":\"Hacienda Los Molinos Boutique Hotel\",\"url\":\"https:\\\/\\\/losmolinoshotel.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/losmolinoshotel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/losmolinoshotel.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo-original.png\",\"contentUrl\":\"https:\\\/\\\/losmolinoshotel.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo-original.png\",\"width\":168,\"height\":100,\"caption\":\"Hacienda Los Molinos Boutique Hotel\"},\"image\":{\"@id\":\"https:\\\/\\\/losmolinoshotel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gallery Los Molinos Boutique Hotel | hotel, spa, events & tours","description":"Explore the gallery of Los Molinos Boutique Hotel. Discover our hotel, spa, events, and tours in Boquete, Chiriqu\u00ed, Panama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/losmolinoshotel.com\/en\/gallery\/","og_locale":"en_US","og_type":"article","og_title":"Gallery Los Molinos Boutique Hotel | hotel, spa, events & tours","og_description":"Explore the gallery of Los Molinos Boutique Hotel. Discover our hotel, spa, events, and tours in Boquete, Chiriqu\u00ed, Panama","og_url":"https:\/\/losmolinoshotel.com\/en\/gallery\/","og_site_name":"Hacienda Los Molinos Boutique Hotel","article_modified_time":"2025-09-16T22:04:12+00:00","og_image":[{"width":1920,"height":705,"url":"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/10\/header_4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/losmolinoshotel.com\/en\/gallery\/","url":"https:\/\/losmolinoshotel.com\/en\/gallery\/","name":"Gallery Los Molinos Boutique Hotel | hotel, spa, events & tours","isPartOf":{"@id":"https:\/\/losmolinoshotel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/losmolinoshotel.com\/en\/gallery\/#primaryimage"},"image":{"@id":"https:\/\/losmolinoshotel.com\/en\/gallery\/#primaryimage"},"thumbnailUrl":"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/10\/header_4.jpg","datePublished":"2016-07-24T09:56:31+00:00","dateModified":"2025-09-16T22:04:12+00:00","description":"Explore the gallery of Los Molinos Boutique Hotel. Discover our hotel, spa, events, and tours in Boquete, Chiriqu\u00ed, Panama","breadcrumb":{"@id":"https:\/\/losmolinoshotel.com\/en\/gallery\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/losmolinoshotel.com\/en\/gallery\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/losmolinoshotel.com\/en\/gallery\/#primaryimage","url":"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/10\/header_4.jpg","contentUrl":"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/10\/header_4.jpg","width":1920,"height":705,"caption":"Cafeter\u00edas en Boquete, Chiriqu\u00ed | Disfruta en Hacienda Los Molinos"},{"@type":"BreadcrumbList","@id":"https:\/\/losmolinoshotel.com\/en\/gallery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/losmolinoshotel.com\/en\/"},{"@type":"ListItem","position":2,"name":"Gallery"}]},{"@type":"WebSite","@id":"https:\/\/losmolinoshotel.com\/#website","url":"https:\/\/losmolinoshotel.com\/","name":"Hacienda Los Molinos Boutique Hotel","description":"Hotel en Boquete, Panam\u00e1","publisher":{"@id":"https:\/\/losmolinoshotel.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/losmolinoshotel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/losmolinoshotel.com\/#organization","name":"Hacienda Los Molinos Boutique Hotel","url":"https:\/\/losmolinoshotel.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/losmolinoshotel.com\/#\/schema\/logo\/image\/","url":"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/05\/logo-original.png","contentUrl":"https:\/\/losmolinoshotel.com\/wp-content\/uploads\/2020\/05\/logo-original.png","width":168,"height":100,"caption":"Hacienda Los Molinos Boutique Hotel"},"image":{"@id":"https:\/\/losmolinoshotel.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/losmolinoshotel.com\/en\/wp-json\/wp\/v2\/pages\/2064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losmolinoshotel.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/losmolinoshotel.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/losmolinoshotel.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/losmolinoshotel.com\/en\/wp-json\/wp\/v2\/comments?post=2064"}],"version-history":[{"count":2,"href":"https:\/\/losmolinoshotel.com\/en\/wp-json\/wp\/v2\/pages\/2064\/revisions"}],"predecessor-version":[{"id":2066,"href":"https:\/\/losmolinoshotel.com\/en\/wp-json\/wp\/v2\/pages\/2064\/revisions\/2066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losmolinoshotel.com\/en\/wp-json\/wp\/v2\/media\/1973"}],"wp:attachment":[{"href":"https:\/\/losmolinoshotel.com\/en\/wp-json\/wp\/v2\/media?parent=2064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}